{"id":81002,"date":"2023-02-13T10:18:03","date_gmt":"2023-02-13T09:18:03","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/sem%20categoria\/pack-2-almofadas-de-espreguicadeira-azul-reciclado\/"},"modified":"2023-08-31T10:11:17","modified_gmt":"2023-08-31T08:11:17","slug":"pack-2-almofadas-espreguicadeira-azul-reciclado","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/","title":{"rendered":"Pack 2 Almofadas de espregui\u00e7adeira azul &#8211; Reciclado"},"content":{"rendered":"<p>Almofadas para espregui\u00e7adeira de jardim 60x190x7cm (largura x comprimento x altura) em azul. As almofadas s\u00e3o remov\u00edveis e lav\u00e1veis na m\u00e1quina, tamb\u00e9m possuem tiras para poder amarrar e fixar a almofada aos m\u00f3veis facilmente. O tecido e enchimento \u00e9 100% poli\u00e9ster reciclado, vem de garrafas e enchimentos reciclados, tecido n\u00e3o imperme\u00e1vel, n\u00e3o adequado para estar constantemente na chuva ou fontes que o mant\u00eam molhado ou molhado. \u00c9 um produto fabricado em Espanha.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Almofadas para espregui\u00e7adeira de jardim 60x190x7cm cor azul<\/li>\n<li>As almofadas s\u00e3o remov\u00edveis e lav\u00e1veis na m\u00e1quina<\/li>\n<li>Tem tiras para amarrar e fixar a almofada<\/li>\n<li>Fabricado em Espanha com tecido e enchimento de poli\u00e9ster 100% reciclado<\/li>\n<\/ul>\n","protected":false},"featured_media":80123,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[415,413],"product_tag":[2347],"class_list":{"0":"post-81002","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-acessorios-ao-ar-livre","7":"product_cat-almofadas-exteriores","8":"product_tag-reciclado","9":"product_shipping_class-envio-gratuito-pt-pt","10":"pa_coleccion-recycled-pt-pt","12":"first","13":"outofstock","14":"sale","15":"purchasable","16":"product-type-simple","17":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama\" \/>\n<meta property=\"og:description\" content=\"Almofadas para espregui\u00e7adeira de jardim 60x190x7cm cor azul  As almofadas s\u00e3o remov\u00edveis e lav\u00e1veis na m\u00e1quina  Tem tiras para amarrar e fixar a almofada  Fabricado em Espanha com tecido e enchimento de poli\u00e9ster 100% reciclado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T08:11:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/\",\"name\":\"Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/b32x2.jpg\",\"datePublished\":\"2023-02-13T09:18:03+00:00\",\"dateModified\":\"2023-08-31T08:11:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/b32x2.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/b32x2.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/pack-2-almofadas-espreguicadeira-azul-reciclado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/tienda-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acess\u00f3rios ao ar livre\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Almofadas exteriores\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/acessorios-ao-ar-livre\\\/almofadas-exteriores\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pack 2 Almofadas de espregui\u00e7adeira azul &#8211; Reciclado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/","og_locale":"pt_PT","og_type":"article","og_title":"Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama","og_description":"Almofadas para espregui\u00e7adeira de jardim 60x190x7cm cor azul  As almofadas s\u00e3o remov\u00edveis e lav\u00e1veis na m\u00e1quina  Tem tiras para amarrar e fixar a almofada  Fabricado em Espanha com tecido e enchimento de poli\u00e9ster 100% reciclado","og_url":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2023-08-31T08:11:17+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/","url":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/","name":"Pack 2 Almofadas de espregui\u00e7adeira azul - Reciclado - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2.jpg","datePublished":"2023-02-13T09:18:03+00:00","dateModified":"2023-08-31T08:11:17+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/pack-2-almofadas-espreguicadeira-azul-reciclado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/keramamueblesdejardin.com\/pt-pt\/tienda-2\/"},{"@type":"ListItem","position":3,"name":"Acess\u00f3rios ao ar livre","item":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/"},{"@type":"ListItem","position":4,"name":"Almofadas exteriores","item":"https:\/\/keramamueblesdejardin.com\/pt-pt\/acessorios-ao-ar-livre\/almofadas-exteriores\/"},{"@type":"ListItem","position":5,"name":"Pack 2 Almofadas de espregui\u00e7adeira azul &#8211; Reciclado"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#website","url":"https:\/\/keramamueblesdejardin.com\/pt-pt\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":149,"df_sale_price":149,"df_regular_price":189,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2023\/02\/b32x2-300x300.jpg","custom_tabs":[{"title":"MEDI\u00c7\u00c3O","id":"medi\u00e7\u00e3o","content":"<div class=\"list\"><strong>Espessura: <\/strong>7cm\n<strong>Largura: <\/strong>190cm\n<strong>Profundidade: <\/strong>60cm<\/div>"},{"title":"MANUTEN\u00c7\u00c3O E GARANTIAS","id":"manutencao-e-garantias","content":"<div class=\"moz-signature\">\n<div class=\"list\">\n\n<strong>Recomenda\u00e7\u00f5es gerais:<\/strong>\n\u2022 Avarias ou danos causados por:\n\u2022 Causas acidentais como quedas, golpes, derrame de l\u00edquidos, introdu\u00e7\u00e3o de corpos estranhos, bem como qualquer outro caso de for\u00e7a maior.\n\u2022 Utiliza\u00e7\u00e3o negligente, impr\u00f3pria ou n\u00e3o dom\u00e9stica.\n\u2022 Danos, corros\u00e3o e\/ou oxida\u00e7\u00e3o acelerada por condi\u00e7\u00f5es ambientais adversas\u2022 Manchas e descolora\u00e7\u00f5es devido ao n\u00e3o cumprimento das nossas instru\u00e7\u00f5es de limpeza\n\u2022 Os danos ocorreram durante a montagem e o manuseamento sem ter seguido as instru\u00e7\u00f5es de montagem indicadas.\n\n<strong>Instru\u00e7\u00f5es de utiliza\u00e7\u00e3o e manuten\u00e7\u00e3o:<\/strong>\n\n\u2022Tecido n\u00e3o imperme\u00e1vel, n\u00e3o adequado para chuva constante ou fontes que o mantenham molhado ou molhado.\n\u2022 Limpe com a ajuda de um pano suavemente ou utilize um sab\u00e3o l\u00edquido neutro, enxaguando com muita \u00e1gua.\n\u2022 Retire regularmente o p\u00f3 com a ajuda de um pano macio e \u00e1gua l\u00edmpia.\n\u2022 N\u00e3o utilize detergentes ou produtos abrasivos para a limpeza.\n<strong>Anos de garantia:<\/strong> 3 anos\n<strong>Fabricado de acordo com a Norma:<\/strong> 581-1.581-2.581-3\n\n<\/div>\n<\/div>"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/product\/81002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=81002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/media\/80123"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=81002"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=81002"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=81002"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=81002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}