{"id":89410,"date":"2021-05-06T08:49:41","date_gmt":"2021-05-06T06:49:41","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/senza-categoria\/ricambio-tessuto-per-ombrellone-300cm-rotondo-naturale-soleggiato\/"},"modified":"2023-08-29T11:53:22","modified_gmt":"2023-08-29T09:53:22","slug":"tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/","title":{"rendered":"Ricambio tessuto per ombrellone 300cm rotondo Naturale &#8211; Soleggiato"},"content":{"rendered":"<p>Tessuto di ricambio per ombrellone 300cm rotondo Naturale 100% poliestere 235g con finitura Teflonado. Facile montaggio e resistente ai raggi UV. Valido per ombrelloni a 8 aste<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Ricambio in tessuto per ombrellone centrale rotondo diametro 300 cm<\/li>\n<li>Tessuto colorato naturale resistente ai raggi UV<\/li>\n<li>100% poliestere 235g con finitura Teflonata<\/li>\n<li>Valido per ombrelloni a 8 aste<\/li>\n<\/ul>\n","protected":false},"featured_media":89413,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2819,2979],"product_tag":[2778,2821],"class_list":{"0":"post-89410","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ombrelloni-e-pergolati","7":"product_cat-ricambi-tessili","8":"product_tag-ampi-spazi","9":"product_tag-assolato","10":"product_shipping_class-envio-gratuito-it","11":"pa_caracteristicas-spiaggia-dellombrellone","12":"pa_coleccion-assolato","13":"pa_material-poliestere","15":"first","16":"instock","17":"sale","18":"purchasable","19":"product-type-simple","20":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama\" \/>\n<meta property=\"og:description\" content=\"Ricambio in tessuto per ombrellone centrale rotondo diametro 300 cm  Tessuto colorato naturale resistente ai raggi UV  100% poliestere 235g con finitura Teflonata  Valido per ombrelloni a 8 aste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-29T09:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2439\" \/>\n\t<meta property=\"og:image:height\" content=\"2059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/\",\"name\":\"Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/KMJ21195-002.jpg\",\"datePublished\":\"2021-05-06T06:49:41+00:00\",\"dateModified\":\"2023-08-29T09:53:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/KMJ21195-002.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/KMJ21195-002.jpg\",\"width\":2439,\"height\":2059},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ombrelloni e pergolati\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ricambi tessili\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/ombrelloni-e-pergolati\\\/ricambi-tessili\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Ricambio tessuto per ombrellone 300cm rotondo Naturale &#8211; Soleggiato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/","og_locale":"it_IT","og_type":"article","og_title":"Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama","og_description":"Ricambio in tessuto per ombrellone centrale rotondo diametro 300 cm  Tessuto colorato naturale resistente ai raggi UV  100% poliestere 235g con finitura Teflonata  Valido per ombrelloni a 8 aste","og_url":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2023-08-29T09:53:22+00:00","og_image":[{"width":2439,"height":2059,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/","url":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/","name":"Ricambio tessuto per ombrellone 300cm rotondo Naturale - Soleggiato - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002.jpg","datePublished":"2021-05-06T06:49:41+00:00","dateModified":"2023-08-29T09:53:22+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002.jpg","width":2439,"height":2059},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/tessuto-replacement-per-ombrellone-300cm-rotondo-naturale-soleggiato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/keramamueblesdejardin.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Ombrelloni e pergolati","item":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/"},{"@type":"ListItem","position":4,"name":"Ricambi tessili","item":"https:\/\/keramamueblesdejardin.com\/it\/ombrelloni-e-pergolati\/ricambi-tessili\/"},{"@type":"ListItem","position":5,"name":"Ricambio tessuto per ombrellone 300cm rotondo Naturale &#8211; Soleggiato"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/it\/#website","url":"https:\/\/keramamueblesdejardin.com\/it\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":59,"df_sale_price":59,"df_regular_price":75,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2021\/04\/KMJ21195-002-300x253.jpg","custom_tabs":[{"title":"MISURAZIONE","id":"misurazione","content":"<strong>Diametro:<\/strong> 3 m\n<strong>Fori stelo:<\/strong> 8"},{"title":"DISIMBALLAGGIO E MONTAGGIO","id":"disimballaggio-e-assemblaggio","content":"<strong>Raccomandazioni per il disimballaggio:<\/strong> Non utilizzare utensili affilati durante il disimballaggio dei mobili in quanto potrebbe causare danni\nRichiede il montaggio (s\u00ec\/no): No"},{"title":"MANUTENZIONE E GARANZIE","id":"manutenzione-e-garanzie","content":"<div class=\"moz-signature\"><div class=\"list\"><strong>Raccomandazioni generali:<\/strong> <br>\u2022 Guasti o danni causati da:<br>\u2022 Cause accidentali come cadute, colpi, fuoriuscite di liquidi, introduzione di corpi estranei, nonch\u00e9 qualsiasi altra causa di forza maggiore.<br>\u2022 Uso negligente, improprio o non domestico.<br>\u2022 Danni, corrosione e\/o ossidazione accelerati da condizioni ambientali avverse<br>\u2022 Macchie e scolorimenti dovuti al mancato rispetto delle nostre istruzioni di pulizia<br>\u2022 Danni verificatisi durante il montaggio e la manipolazione senza aver seguito le istruzioni di montaggio indicate.<br><strong>Istruzioni per l'uso e la manutenzione:<\/strong> <br>\u2022 Pulire delicatamente con l'aiuto di un panno o utilizzare un sapone liquido neutro, risciacquando con abbondante acqua.<br>\u2022 Rimuovere regolarmente la polvere con l'aiuto di un panno morbido e acqua pulita.<br>\u2022 Non utilizzare detergenti o prodotti abrasivi per la pulizia.<br><strong>Anni di garanzia:<\/strong> 3 anni<br><strong>Prodotto secondo lo standard:<\/strong> 581-1,581-2,581-3<\/div><\/div>","name":"Manutenzione e garanzie"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product\/89410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/comments?post=89410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media\/89413"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media?parent=89410"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_brand?post=89410"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_cat?post=89410"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_tag?post=89410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}