{"id":154415,"date":"2024-04-02T16:10:16","date_gmt":"2024-04-02T14:10:16","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/senza-categoria\/set-da-pranzo-da-giardino-6-posti-tavolo-in-ceramica-senape-168x87-ceramik-modena\/"},"modified":"2025-01-15T11:24:12","modified_gmt":"2025-01-15T10:24:12","slug":"apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/","title":{"rendered":"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168&#215;87 &#8211; Ceramik &amp; Modena"},"content":{"rendered":"<p>Set di tavolo da esterno e 6 sedie Modena. I tavoli della famiglia Ceramik sono realizzati con una robusta struttura in legno di acacia di colore chiaro e con un piano in ceramica smaltata lavorata a mano con dimensioni di 20x20cm. Le ceramiche fatte a mano a Girona sono la ragion d&#8217;essere della collezione Ceramik. La combinazione di entrambi gli elementi si traduce in pezzi unici in grado di adattarsi a tutti i tipi di stili di decorazione e vestire con gusto il tuo terrazzo o giardino. Le sedie della collezione Modena sono state progettate ed eseguite in legno di teak certificato FSC, accompagnate da un bellissimo e pratico rattan sintetico di colore beige intrecciato a mano dai nostri artigiani. Misure: Tavolo: 168x87x75cm, Sedia: 45x58x85cm<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Set composto da un tavolo e 6 sedie in legno e rattan<\/li>\n<li>Piano del tavolo in ceramica senape<\/li>\n<li>Sedile e schienale in rattan sintetico  <\/li>\n<li>  Dimensioni : 168x87x75 cm e 45x58x85cm<\/li>\n<\/ul>\n","protected":false},"featured_media":148529,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2775,2776],"product_tag":[2936,5247,2784,5258,2831],"class_list":{"0":"post-154415","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sale-da-pranzo-allaperto","7":"product_cat-set-di-tavoli-e-sedie-da-giardino","8":"product_tag-ceramica-it","9":"product_tag-ceramik-it-2","10":"product_tag-legno","11":"product_tag-modena-it","12":"product_tag-rattan-it","13":"product_shipping_class-envio-gratuito-it","14":"pa_alto-74-it","15":"pa_ancho-167-it","16":"pa_asientos-6-it","17":"pa_coleccion-creamik-it","18":"pa_coleccion-modena-it","19":"pa_espacio-4008-it","20":"pa_forma-rettangolare","21":"pa_largo-240-it","22":"pa_m2-4008-it","23":"pa_material-ceramica-it","24":"pa_material-legno","25":"pa_material-rattan","26":"pa_tamano-espacio-grande-it","28":"first","29":"instock","30":"sale","31":"purchasable","32":"product-type-simple","33":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama\" \/>\n<meta property=\"og:description\" content=\"Set composto da un tavolo e 6 sedie in legno e rattan      Piano del tavolo in ceramica senape      Sedile e schienale in rattan sintetico        Dimensioni : 168x87x75 cm e 45x58x85cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T10:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/\",\"name\":\"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"datePublished\":\"2024-04-02T14:10:16+00:00\",\"dateModified\":\"2025-01-15T10:24:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sale da pranzo all'aperto\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Set di tavoli e sedie da giardino\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/sale-da-pranzo-allaperto\\\/set-di-tavoli-e-sedie-da-giardino\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168&#215;87 &#8211; Ceramik &amp; Modena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/","og_locale":"it_IT","og_type":"article","og_title":"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama","og_description":"Set composto da un tavolo e 6 sedie in legno e rattan      Piano del tavolo in ceramica senape      Sedile e schienale in rattan sintetico        Dimensioni : 168x87x75 cm e 45x58x85cm","og_url":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2025-01-15T10:24:12+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/","url":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/","name":"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168x87 - Ceramik &amp; Modena - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","datePublished":"2024-04-02T14:10:16+00:00","dateModified":"2025-01-15T10:24:12+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/apparecchiato-pranzo-giardino-tavolo-6-posti-ceramica-senape-168x87-ceramik-modena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/keramamueblesdejardin.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Sale da pranzo all'aperto","item":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/"},{"@type":"ListItem","position":4,"name":"Set di tavoli e sedie da giardino","item":"https:\/\/keramamueblesdejardin.com\/it\/sale-da-pranzo-allaperto\/set-di-tavoli-e-sedie-da-giardino\/"},{"@type":"ListItem","position":5,"name":"Set da pranzo da giardino 6 posti tavolo in ceramica senape 168&#215;87 &#8211; Ceramik &amp; Modena"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/it\/#website","url":"https:\/\/keramamueblesdejardin.com\/it\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":1679,"df_sale_price":1679,"df_regular_price":1997,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza-300x300.jpg","custom_tabs":[{"title":"MISURAZIONE","id":"misurazione","content":"<div class=\"list\">\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">Altezza: <\/strong>tavolo 75cm \/ sedia 85cm<\/div>\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">Larghezza: <\/strong>tavolo 168cm \/ sedia 45cm<\/div>\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">Fondo: <\/strong>tavolo 87cm \/ sedia 58cm<\/div>\n<\/div>"},{"title":"DISIMBALLAGGIO E MONTAGGIO","id":"disimballaggio-e-assemblaggio","content":"<div class=\"list\"><strong style=\"font-weight: bold; color: #282828;\">Raccomandazioni per<\/strong> il disimballaggio: <span style=\"color: #282828;\"> Non utilizzare utensili affilati durante il disimballaggio dei mobili in quanto potrebbe causare danni<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Richiede il montaggio (s\u00ec\/no):<\/strong><span style=\"color: #282828;\"> S\u00ec<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Difficolt\u00e0 di montaggio:<\/strong><span style=\"color: #282828;\"> Bassa<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Tempo di assemblaggio:<\/strong><span style=\"color: #282828;\"> 40 minuti<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Persone consigliate per il montaggio:<\/strong><span style=\"color: #282828;\"> 2<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Suggerimenti di montaggio:<\/strong><span style=\"color: #282828;\">  Preparare un'area di assemblaggio pulita e asciutta, verificare che nessuna delle parti indicate nel manuale manchi. Si consiglia di indossare guanti adatti al montaggio. Utilizzare solo le parti e l'hardware in dotazione.<\/span><\/div>"},{"title":"MANUTENZIONE E GARANZIE","id":"manutenzione-e-garanzie","content":"<strong>Raccomandazioni generali:<\/strong>\n\u2022 Guasti o danni causati da:\n\u2022 Cause accidentali come cadute, colpi, fuoriuscite di liquidi, introduzione di corpi estranei, nonch\u00e9 qualsiasi altra causa di forza maggiore.\n\u2022 Uso negligente, improprio o non domestico.\n\u2022 Danni, corrosione e\/o ossidazione accelerati da condizioni ambientali avverse\n\u2022 Macchie e scolorimenti dovuti al mancato rispetto delle nostre istruzioni di pulizia\n\u2022 Danni verificatisi durante il montaggio e la manipolazione senza aver seguito le istruzioni di montaggio indicate.\n<strong>Istruzioni per l'uso e la manutenzione:<\/strong>\n\u2022 Pulire delicatamente con l'aiuto di un panno o utilizzare un sapone liquido neutro, risciacquando con abbondante acqua.\n\u2022 Rimuovere regolarmente la polvere con l'aiuto di un panno morbido e acqua pulita.\n\u2022 Non utilizzare detergenti o prodotti abrasivi per la pulizia.\n\u2022 Trattamento con olio di lino: Prima di applicare uno strato di olio di lino sul prodotto allo stato naturale \u00e8 consigliabile lasciarlo all'esterno per 2 o 3 settimane, in modo da assumere un aspetto omogeneo e aerarlo. Pulire con acqua pulita usando un pennello e lasciare asciugare. Una volta ben asciutto, va carteggiato con una carta vetrata di grammatura tra 120 e 150 con cura e senza stringere, seguendo, per quanto possibile, la direzione delle vene; Questa operazione non viene mai eseguita nelle prime ore del giorno.\nPer mantenere il colore \u00e8 consigliabile ripetere il processo una o due volte l'anno.\nSe l'olio di lino \u00e8 gi\u00e0 stato applicato ai mobili \u00e8 consigliabile carteggiarlo ogni tre anni in modo che gli strati successivi di olio non impediscano la traspirazione del legno.\n<strong>Anni di garanzia:<\/strong> 3 anni\n<strong>Prodotto secondo lo standard:<\/strong> 581-1,581-2,581-3\n<strong>Certificazione FSC (s\u00ec\/no):<\/strong> S\u00ec"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product\/154415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/comments?post=154415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media\/148529"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media?parent=154415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_brand?post=154415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_cat?post=154415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_tag?post=154415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}