{"id":153082,"date":"2024-04-02T16:04:48","date_gmt":"2024-04-02T14:04:48","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/senza-categoria\/tavolino-da-giardino-rotondo-105cm-corda-e-cemento-bergamo\/"},"modified":"2024-10-02T16:37:47","modified_gmt":"2024-10-02T14:37:47","slug":"tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/","title":{"rendered":"Tavolino da giardino rotondo 105cm corda e cemento &#8211; Bergamo"},"content":{"rendered":"<p>Tavolino rotondo da giardino della collezione Bergamo con struttura in alluminio e corda intrecciata con piano finitura pietra grigia. La collezione Corf\u00f9 gravita attorno alle sue linee organiche senza spigoli e leggere curve accompagnate da corda intrecciata a mano dai nostri artigiani. I cuscini extra spessi offrono un comfort eccezionale per goderti le tue giornate all&#8217;aperto con i tuoi cari. Misure: D105x37cm<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Tavolo in alluminio grigio e corda<\/li>\n<li>Piano del tavolo con finitura in pietra grigia<\/li>\n<li>Misure: 105x37cm<\/li>\n<\/ul>\n","protected":false},"featured_media":151265,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2812,2830],"product_tag":[2901,2778,5148,3681],"class_list":{"0":"post-153082","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-saloni-allaperto","7":"product_cat-tavolini-da-giardino","8":"product_tag-alluminio","9":"product_tag-ampi-spazi","10":"product_tag-bergamo-it","11":"product_tag-corda-it","12":"product_shipping_class-envio-gratuito-it","13":"pa_alto-37-it","14":"pa_ancho-105-it","15":"pa_coleccion-bergamo-it","16":"pa_forma-rotondo-it","17":"pa_largo-105-it","18":"pa_material-alluminio","19":"pa_material-corda","21":"first","22":"instock","23":"sale","24":"purchasable","25":"product-type-simple","26":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama\" \/>\n<meta property=\"og:description\" content=\"Tavolo in alluminio grigio e corda  Piano del tavolo con finitura in pietra grigia  Misure: 105x37cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T14:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/\",\"name\":\"Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/corfu-mesa-grande.jpg\",\"datePublished\":\"2024-04-02T14:04:48+00:00\",\"dateModified\":\"2024-10-02T14:37:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/corfu-mesa-grande.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/corfu-mesa-grande.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Saloni all'aperto\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tavolini da giardino\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/saloni-allaperto\\\/tavolini-da-giardino\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Tavolino da giardino rotondo 105cm corda e cemento &#8211; Bergamo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/","og_locale":"it_IT","og_type":"article","og_title":"Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama","og_description":"Tavolo in alluminio grigio e corda  Piano del tavolo con finitura in pietra grigia  Misure: 105x37cm","og_url":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2024-10-02T14:37:47+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/","url":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/","name":"Tavolino da giardino rotondo 105cm corda e cemento - Bergamo - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande.jpg","datePublished":"2024-04-02T14:04:48+00:00","dateModified":"2024-10-02T14:37:47+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/tavolino-basso-rotondo-giardino-105cm-corda-e-cemento-bergamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/keramamueblesdejardin.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Saloni all'aperto","item":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/"},{"@type":"ListItem","position":4,"name":"Tavolini da giardino","item":"https:\/\/keramamueblesdejardin.com\/it\/saloni-allaperto\/tavolini-da-giardino\/"},{"@type":"ListItem","position":5,"name":"Tavolino da giardino rotondo 105cm corda e cemento &#8211; Bergamo"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/it\/#website","url":"https:\/\/keramamueblesdejardin.com\/it\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/it\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":539,"df_sale_price":539,"df_regular_price":641,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/corfu-mesa-grande-300x300.jpg","custom_tabs":[{"title":"MISURAZIONE","id":"misurazione","content":"<div class=\"list\"><strong>Altezza: <\/strong>37cm<\/div>\n<div class=\"list\"><strong>Larghezza: <\/strong>105cm<\/div>\n<div class=\"list\"><strong>Profondit\u00e0: <\/strong>105cm<\/div>"},{"title":"DISIMBALLAGGIO E MONTAGGIO","id":"disimballaggio-e-assemblaggio","content":"<div class=\"list\"><strong style=\"font-weight: bold; color: #282828;\">Raccomandazioni per<\/strong> il disimballaggio: <span style=\"color: #282828;\"> Non utilizzare utensili affilati durante il disimballaggio dei mobili in quanto potrebbe causare danni<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Richiede il montaggio (s\u00ec\/no):<\/strong><span style=\"color: #282828;\"> No<\/span><\/div>"},{"title":"MANUTENZIONE E GARANZIE","id":"manutenzione-e-garanzie","content":"<div class=\"moz-signature\">\n<div class=\"list\"><strong>Raccomandazioni generali:<\/strong>\n\u2022 Guasti o danni causati da:\n\u2022 Cause accidentali come cadute, colpi, fuoriuscite di liquidi, introduzione di corpi estranei, nonch\u00e9 qualsiasi altra causa di forza maggiore.\n\u2022 Uso negligente, improprio o non domestico.\n\u2022 Danni, corrosione e\/o ossidazione accelerati da condizioni ambientali avverse\n\u2022 Macchie e scolorimenti dovuti al mancato rispetto delle nostre istruzioni di pulizia\n\u2022 Danni verificatisi durante il montaggio e la manipolazione senza aver seguito le istruzioni di montaggio indicate.\n<strong>Istruzioni per l'uso e la manutenzione:<\/strong>\n\u2022 Pulire delicatamente con l'aiuto di un panno o utilizzare un sapone liquido neutro, risciacquando con abbondante acqua.\n\u2022 Rimuovere regolarmente la polvere con l'aiuto di un panno morbido e acqua pulita.\n\u2022 Non utilizzare detergenti o prodotti abrasivi per la pulizia.\n<strong>Anni di garanzia:<\/strong> 3 anni\n<strong>Prodotto secondo lo standard:<\/strong> 581-1,581-2,581-3<\/div>\n<\/div>"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product\/153082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/comments?post=153082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media\/151265"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/media?parent=153082"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_brand?post=153082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_cat?post=153082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/it\/wp-json\/wp\/v2\/product_tag?post=153082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}