{"id":78281,"date":"2022-09-13T15:23:57","date_gmt":"2022-09-13T13:23:57","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/non%20class\u00e9\/ensemble-de-jardin-2-canapes-pour-3-personnes-2-fauteuils-1-table-basse-en-bois-riviera-bologneriviera\/"},"modified":"2024-12-02T15:48:57","modified_gmt":"2024-12-02T14:48:57","slug":"ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/","title":{"rendered":"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera &#8211; Bologne&amp;Riviera"},"content":{"rendered":"<p>L\u2019ensemble de mobilier d\u2019ext\u00e9rieur pour jardin ou terrasse Bologne est en aluminium recouvert de rotin synth\u00e9tique en baige brun.<br \/>\nL\u2019ensemble a une capacit\u00e9 de 8 personnes, car il dispose de 2 canap\u00e9s 3 places + 2 fauteuils et une table basse en bois.<br \/>\nLes mat\u00e9riaux de l\u2019assemblage sont r\u00e9sistants et faciles \u00e0 nettoyer et en m\u00eame temps, gr\u00e2ce \u00e0 leur construction l\u00e9g\u00e8re, toutes les pi\u00e8ces peuvent \u00eatre d\u00e9plac\u00e9es facilement. Les coussins sont amovibles en polyester 230g et lavables.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Structure en aluminium et rotin synth\u00e9tique beige brun<\/li>\n<li>2 canap\u00e9s 3 places + 2 fauteuils + table basse en bois<\/li>\n<li>Coussins amovibles, beiges<\/li>\n<li>Vous pouvez le combiner avec d\u2019autres \u00e9l\u00e9ments de la famille Bologne<\/li>\n<\/ul>\n","protected":false},"featured_media":76189,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[604,599],"product_tag":[581,828,567,595,628],"class_list":{"0":"post-78281","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-salles-exterieures","7":"product_cat-ensembles-de-jardin","8":"product_tag-bois","9":"product_tag-bologne","10":"product_tag-grands-espaces","11":"product_tag-riviera-fr","12":"product_tag-rotin","13":"product_shipping_class-envio-gratuito-fr","14":"pa_asientos-8-fr","15":"pa_caracteristicas-housses-lavables","16":"pa_coleccion-bolonia-fr","17":"pa_coleccion-riviera-fr","18":"pa_material-madera-fr","19":"pa_material-ratan-fr","20":"pa_tamano-espacio-grand","22":"first","23":"instock","24":"sale","25":"purchasable","26":"product-type-simple","27":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama\" \/>\n<meta property=\"og:description\" content=\"Structure en aluminium et rotin synth\u00e9tique beige brun  2 canap\u00e9s 3 places + 2 fauteuils + table basse en bois  Coussins amovibles, beiges  Vous pouvez le combiner avec d\u2019autres \u00e9l\u00e9ments de la famille Bologne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T14:48:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/\",\"name\":\"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg\",\"datePublished\":\"2022-09-13T13:23:57+00:00\",\"dateModified\":\"2024-12-02T14:48:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salles ext\u00e9rieures\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ensembles de jardin\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/salles-exterieures\\\/ensembles-de-jardin\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera &#8211; Bologne&amp;Riviera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/","og_locale":"fr_FR","og_type":"article","og_title":"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama","og_description":"Structure en aluminium et rotin synth\u00e9tique beige brun  2 canap\u00e9s 3 places + 2 fauteuils + table basse en bois  Coussins amovibles, beiges  Vous pouvez le combiner avec d\u2019autres \u00e9l\u00e9ments de la famille Bologne","og_url":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2024-12-02T14:48:57+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/","url":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/","name":"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera - Bologne&amp;Riviera - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg","datePublished":"2022-09-13T13:23:57+00:00","dateModified":"2024-12-02T14:48:57+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-e1697463316394.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/ensemble-de-jardin-2-canapes-de-3-places-2-fauteuils-1-table-basse-bois-riviera-bologneriviera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/keramamueblesdejardin.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Salles ext\u00e9rieures","item":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/"},{"@type":"ListItem","position":4,"name":"Ensembles de jardin","item":"https:\/\/keramamueblesdejardin.com\/fr\/salles-exterieures\/ensembles-de-jardin\/"},{"@type":"ListItem","position":5,"name":"Ensemble de jardin 2 canap\u00e9s pour 3 personnes + 2 fauteuils + 1 table basse en bois Riviera &#8211; Bologne&amp;Riviera"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/fr\/#website","url":"https:\/\/keramamueblesdejardin.com\/fr\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/fr\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/keramamueblesdejardin.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":2249,"df_sale_price":2249,"df_regular_price":2768,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2022\/09\/bolonia-8-sof-riviera-bajo-300x300.jpg","custom_tabs":[{"title":"MESURES","id":"mesures","content":"<div class=\"list\"><strong>Hauteur:<\/strong> canap\u00e9 3 places 78cm \/ fauteuil 78cm \/ m \/ table 36cm\n<strong>Largeur:<\/strong> canap\u00e9 3 places 204cm \/ fauteuil 84cm \/ table 127.5cm\n<strong>Profond:<\/strong> canap\u00e9 3 places 84cm \/ fauteuil 84cm \/ table 65cm<\/div>\n<div>\n<div><strong>Hauteur d\u2019assise: <\/strong>45cm<\/div>\n<div><strong>Profondeur d\u2019assise avec coussin: <\/strong>51cm<\/div>\n<div><strong>Profondeur d\u2019assise sans <\/strong><b>coussin: <\/b>62cm<\/div>\n<\/div>"},{"title":"D\u00c9BALLAGE ET MONTAGE","id":"deballage-et-montage","content":"<div class=\"list\"><strong style=\"font-weight: bold; color: #282828;\">Recommandations pour le d\u00e9ballage :<\/strong><span style=\"color: #282828;\"> N'utilisez pas d'outils tranchants lors du d\u00e9ballage du meuble, car cela pourrait l'endommager.<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Montage requis (O\/N) :<\/strong><span style=\"color: #282828;\"> Oui<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Difficult\u00e9 de montage :<\/strong><span style=\"color: #282828;\"> Moyen<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Temps de montage :<\/strong><span style=\"color: #282828;\"> 90 minutes<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Personnes recommand\u00e9es pour le montage :<\/strong><span style=\"color: #282828;\"> 2<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Suggestions de montage :<\/strong><span style=\"color: #282828;\">  Pr\u00e9parez une zone de montage propre et s\u00e8che, v\u00e9rifiez qu'aucune des pi\u00e8ces \u00e9num\u00e9r\u00e9es dans le manuel ne manque. Nous recommandons l'utilisation de gants appropri\u00e9s pour le montage. N'utilisez que les pi\u00e8ces et les raccords fournis. Nous ne recommandons PAS l'option d'achat avec montage pour cet article car la difficult\u00e9 de montage est tr\u00e8s faible.<\/span><\/div>"},{"title":"ENTRETIEN ET GARANTIES","id":"entretien-et-garanties","content":"<strong>Recommandations g\u00e9n\u00e9rales :<\/strong>\n- Les d\u00e9faillances ou les dommages caus\u00e9s par les \u00e9l\u00e9ments suivants sont exclus de la garantie :\n- Les causes accidentelles telles que chutes, coups, d\u00e9versement de liquides, introduction de corps \u00e9trangers, ainsi que toute autre force majeure.\n- Utilisation n\u00e9gligente, inappropri\u00e9e ou non domestique.\n- Dommages, corrosion et\/ou oxydation acc\u00e9l\u00e9r\u00e9s par des conditions environnementales d\u00e9favorables.\n- Taches et d\u00e9coloration dues au non-respect de nos instructions de nettoyage.\n- Dommages survenus lors du montage et de la manipulation sans respecter les instructions de montage.\n<strong>Instructions d'utilisation et d'entretien :<\/strong>\n- Essuyez doucement avec un chiffon ou utilisez un savon liquide neutre, puis rincez abondamment \u00e0 l'eau.\n- Enlevez r\u00e9guli\u00e8rement la poussi\u00e8re avec un chiffon doux et de l'eau claire.\n- N'utilisez pas de d\u00e9tergents ou de produits abrasifs pour le nettoyage.\n- Traitement \u00e0 l'huile de lin : Avant d'appliquer une couche d'huile de lin sur le produit \u00e0 l'\u00e9tat naturel, il est conseill\u00e9 de le laisser \u00e0 l'ext\u00e9rieur pendant 2 \u00e0 3 semaines afin de lui donner un aspect homog\u00e8ne et de l'a\u00e9rer. Nettoyer \u00e0 l'eau claire \u00e0 l'aide d'une brosse et laisser s\u00e9cher. Une fois qu'elle est bien s\u00e8che, poncez-la avec une feuille de papier de verre d'un grammage compris entre 120 et 150, avec pr\u00e9caution et sans appuyer, en suivant, autant que possible, le sens des veines ; cette op\u00e9ration ne doit jamais \u00eatre effectu\u00e9e aux premi\u00e8res heures du jour.\nPour conserver la couleur, il est conseill\u00e9 de r\u00e9p\u00e9ter le processus une ou deux fois par an.\nSi l'huile de lin a d\u00e9j\u00e0 \u00e9t\u00e9 appliqu\u00e9e sur le meuble, il est conseill\u00e9 de le poncer tous les trois ans afin que les couches successives d'huile n'emp\u00eachent pas le bois de transpirer.\n<strong>Ann\u00e9es de garantie :<\/strong> 3 ans\n<strong>Fabriqu\u00e9 conform\u00e9ment \u00e0 la norme :<\/strong> 581-1,581-2,581-3\n<strong>Certifi\u00e9 FSC (O\/N) :<\/strong> Oui"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/product\/78281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/comments?post=78281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/media\/76189"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/media?parent=78281"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/product_brand?post=78281"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/product_cat?post=78281"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/fr\/wp-json\/wp\/v2\/product_tag?post=78281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}