{"id":165809,"date":"2024-05-23T17:05:18","date_gmt":"2024-05-23T15:05:18","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/unkategorisiert\/beigefarbener-gartentisch-aus-synthetischem-rattan-simbabwe\/"},"modified":"2024-10-04T12:19:54","modified_gmt":"2024-10-04T10:19:54","slug":"niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/","title":{"rendered":"Beigefarbener Gartentisch aus synthetischem Rattan &#8211; Simbabwe"},"content":{"rendered":"<p>Gartengarnitur bestehend aus 1 Dreisitzer-Sofa, zwei Sesseln und einem niedrigen Tisch. Die St\u00fccke der Simbabwe-Kollektion werden mit einer epoxidlackierten Aluminiumstruktur hergestellt, um ihre Haltbarkeit zu erh\u00f6hen, diese Struktur ist in ein Handgeflecht aus dickem synthetischem Rattan in beiger Farbe gewickelt. Die Kissen der Simbabwe-Kollektion sind beige und wasserabweisend behandelt, abnehmbar und waschbar.<br \/>\nDie Simbabwe-Kollektion muss nicht zusammengebaut werden, muss also nur ausgepackt und genossen werden.<\/p>\n<p>Ma\u00dfe: 119&#215;58,5&#215;43 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Beigefarbener Couchtisch aus synthetischem Rattan<\/li>\n<li>Aluminiumstruktur ohne Montage<\/li>\n<li>Platte aus geh\u00e4rtetem Glas<\/li>\n<li>Ma\u00dfe: 119&#215;58,5&#215;43 cm<\/li>\n<\/ul>\n","protected":false},"featured_media":160391,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3293,3234],"product_tag":[3264,3753,6042],"class_list":{"0":"post-165809","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-beistelltische-fur-den-garten","7":"product_cat-lounges-im-freien","8":"product_tag-holz","9":"product_tag-seil","10":"product_tag-zimbabwe-de","11":"product_shipping_class-envio-gratuito-de","12":"pa_alto-43-de","13":"pa_ancho-58-de","14":"pa_coleccion-zimbabwe-de","15":"pa_forma-rechteckig","16":"pa_largo-119-de","17":"pa_material-rattan-de","19":"first","20":"outofstock","21":"sale","22":"purchasable","23":"product-type-simple","24":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama\" \/>\n<meta property=\"og:description\" content=\"Beigefarbener Couchtisch aus synthetischem Rattan  Aluminiumstruktur ohne Montage  Platte aus geh\u00e4rtetem Glas  Ma\u00dfe: 119x58,5x43 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-04T10:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/\",\"name\":\"Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Pro-Capture-One-1865.jpg\",\"datePublished\":\"2024-05-23T15:05:18+00:00\",\"dateModified\":\"2024-10-04T10:19:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Pro-Capture-One-1865.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Pro-Capture-One-1865.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Simbabwe Gartentisch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laden\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/laden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lounges im Freien\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Beistelltische f\u00fcr den Garten\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/lounges-im-freien\\\/beistelltische-fur-den-garten\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Beigefarbener Gartentisch aus synthetischem Rattan &#8211; Simbabwe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/","og_locale":"de_DE","og_type":"article","og_title":"Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama","og_description":"Beigefarbener Couchtisch aus synthetischem Rattan  Aluminiumstruktur ohne Montage  Platte aus geh\u00e4rtetem Glas  Ma\u00dfe: 119x58,5x43 cm","og_url":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2024-10-04T10:19:54+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/","url":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/","name":"Beigefarbener Gartentisch aus synthetischem Rattan - Simbabwe - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865.jpg","datePublished":"2024-05-23T15:05:18+00:00","dateModified":"2024-10-04T10:19:54+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865.jpg","width":1200,"height":1200,"caption":"Simbabwe Gartentisch"},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/niedriger-garten-rattan-kunststoff-beige-simbabwe-tisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/de\/"},{"@type":"ListItem","position":2,"name":"Laden","item":"https:\/\/keramamueblesdejardin.com\/de\/laden\/"},{"@type":"ListItem","position":3,"name":"Lounges im Freien","item":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/"},{"@type":"ListItem","position":4,"name":"Beistelltische f\u00fcr den Garten","item":"https:\/\/keramamueblesdejardin.com\/de\/lounges-im-freien\/beistelltische-fur-den-garten\/"},{"@type":"ListItem","position":5,"name":"Beigefarbener Gartentisch aus synthetischem Rattan &#8211; Simbabwe"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/de\/#website","url":"https:\/\/keramamueblesdejardin.com\/de\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/de\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/keramamueblesdejardin.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":339,"df_sale_price":339,"df_regular_price":410,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/05\/Pro-Capture-One-1865-300x300.jpg","custom_tabs":[{"title":"MESSUNG","id":"messung","content":"<div class=\"list\"><strong>Hoch: <\/strong>Tisch: 43cm<\/div>\n<div class=\"list\"><strong>Breit: <\/strong>Tisch: 119cm<\/div>\n<div class=\"list\"><strong>Unteres:<\/strong> Tisch: 158,5cm<\/div>"},{"title":"AUSPACKEN UND MONTIEREN","id":"auspacken-und-montieren","content":"<div class=\"list\"><strong style=\"font-weight: bold; color: #282828;\">Empfehlungen zum<\/strong> Auspacken: <span style=\"color: #282828;\"> Verwenden Sie beim Auspacken der M\u00f6bel keine scharfen Utensilien, da dies zu Besch\u00e4digungen f\u00fchren kann<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Montage erforderlich (ja\/nein):<\/strong><span style=\"color: #282828;\"> Nein<\/span><\/div>"},{"title":"WARTUNG UND GARANTIEN","id":"wartung-und-garantien","content":"<div class=\"moz-signature\">\n<div class=\"list\"><strong>Allgemeine Empfehlungen:<\/strong>\n\u2022 Pannen oder Sch\u00e4den, die verursacht werden durch:\n\u2022 Zuf\u00e4llige Ursachen wie St\u00fcrze, Schl\u00e4ge, Versch\u00fctten von Fl\u00fcssigkeiten, Einschleppen von Fremdk\u00f6rpern sowie andere h\u00f6here Gewalt.\n\u2022 Fahrl\u00e4ssiger, unsachgem\u00e4\u00dfer oder nicht h\u00e4uslicher Gebrauch.\n\u2022 Besch\u00e4digung, Korrosion und\/oder Oxidation beschleunigt durch widrige Umweltbedingungen\n\u2022 Flecken und Verf\u00e4rbungen durch Nichtbeachtung unserer Reinigungsanweisungen\n\u2022 Sch\u00e4den, die w\u00e4hrend der Montage und Handhabung auftreten, ohne die angegebenen Montageanweisungen befolgt zu haben.\n<strong>Gebrauchs- und Wartungshinweise:<\/strong>\n\u2022 Reinigen Sie mit Hilfe eines Tuchs vorsichtig oder verwenden Sie eine neutrale Fl\u00fcssigseife und sp\u00fclen Sie sie mit viel Wasser ab.\n\u2022 Entfernen Sie Staub regelm\u00e4\u00dfig mit Hilfe eines weichen Tuchs und klarem Wasser.\n\u2022 Verwenden Sie zum Reinigen keine Reinigungsmittel oder Scheuermittel.\nJahre <strong>Garantie: 3 Jahre<\/strong>\n<strong>Hergestellt nach Norm:<\/strong> 581-1.581-2.581-3<\/div>\n<\/div>"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product\/165809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/comments?post=165809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/media\/160391"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/media?parent=165809"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_brand?post=165809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_cat?post=165809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_tag?post=165809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}