{"id":154412,"date":"2024-04-02T16:10:16","date_gmt":"2024-04-02T14:10:16","guid":{"rendered":"https:\/\/keramamueblesdejardin.com\/unkategorisiert\/garten-esszimmergarnitur-6-sitzer-keramik-senftisch-168x87-ceramik-modena\/"},"modified":"2025-01-15T11:24:03","modified_gmt":"2025-01-15T10:24:03","slug":"set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena","status":"publish","type":"product","link":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/","title":{"rendered":"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168&#215;87 &#8211; Ceramik &amp; Modena"},"content":{"rendered":"<p>Set aus Tisch f\u00fcr den Au\u00dfenbereich und 6 Modena-St\u00fchlen. Die Tische der Familie Ceramik sind mit einer robusten Struktur aus hellem Akazienholz und mit einer handgefertigten glasierten Keramikplatte mit den Ma\u00dfen 20x20cm gefertigt. Handgefertigte Keramik, die in Girona hergestellt wird, ist die Daseinsberechtigung der Ceramik-Kollektion. Die Kombination beider Elemente f\u00fchrt zu einzigartigen St\u00fccken, die sich in alle Arten von Dekorationsstilen einf\u00fcgen und Ihre Terrasse oder Ihren Garten geschmackvoll gestalten. Die St\u00fchle der Modena-Kollektion wurden aus FSC-zertifiziertem Teakholz entworfen und ausgef\u00fchrt, begleitet von einem sch\u00f6nen und praktischen synthetischen Rattan in Beige, das von unseren Kunsthandwerkern handgeflochten wurde. Ma\u00dfe: Tisch: 168x87x75cm, Stuhl: 45x58x85cm<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Set bestehend aus einem Tisch und 6 St\u00fchlen aus Holz und Rattan<\/li>\n<li>Senffarbene Keramik-Tischplatte<\/li>\n<li>Sitz und R\u00fcckenlehne aus synthetischem Rattan  <\/li>\n<li>  Ma\u00dfe : 168x87x75 cm und 45x58x85cm<\/li>\n<\/ul>\n","protected":false},"featured_media":148528,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3241,3238],"product_tag":[3264,3409,5122,5120,3284],"class_list":{"0":"post-154412","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gartentisch-und-stuhlgarnitur","7":"product_cat-speisesale-im-freien","8":"product_tag-holz","9":"product_tag-keramik","10":"product_tag-keramik-de","11":"product_tag-modena-de","12":"product_tag-rattan-de","13":"product_shipping_class-envio-gratuito-de","14":"pa_alto-74-de","15":"pa_ancho-167-de","16":"pa_asientos-6-de","17":"pa_coleccion-creamik-de","18":"pa_coleccion-modena-de","19":"pa_espacio-4008-de","20":"pa_forma-rechteckig","21":"pa_largo-240-de","22":"pa_m2-4008-de","23":"pa_material-holz","24":"pa_material-keramik","25":"pa_material-rattan-de","26":"pa_tamano-espacio-gros","28":"first","29":"instock","30":"sale","31":"purchasable","32":"product-type-simple","33":"add-to-wishlist-before_image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama\" \/>\n<meta property=\"og:description\" content=\"Set bestehend aus einem Tisch und 6 St\u00fchlen aus Holz und Rattan      Senffarbene Keramik-Tischplatte      Sitz und R\u00fcckenlehne aus synthetischem Rattan        Ma\u00dfe : 168x87x75 cm und 45x58x85cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/\" \/>\n<meta property=\"og:site_name\" content=\"Kerama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T10:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/\",\"name\":\"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"datePublished\":\"2024-04-02T14:10:16+00:00\",\"dateModified\":\"2025-01-15T10:24:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/168-6-modena-mostaza.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laden\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/laden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Speises\u00e4le im Freien\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Gartentisch- und Stuhlgarnitur\",\"item\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/speisesale-im-freien\\\/gartentisch-und-stuhlgarnitur\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168&#215;87 &#8211; Ceramik &amp; Modena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\",\"name\":\"Kerama\",\"description\":\"muebles de jard\u00edn\",\"publisher\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#organization\",\"name\":\"kerama\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/k.-scaled.jpg\",\"width\":2560,\"height\":551,\"caption\":\"kerama\"},\"image\":{\"@id\":\"https:\\\/\\\/keramamueblesdejardin.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kerama-Muebles-de-Jard\u00edn-106209328312568\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/","og_locale":"de_DE","og_type":"article","og_title":"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama","og_description":"Set bestehend aus einem Tisch und 6 St\u00fchlen aus Holz und Rattan      Senffarbene Keramik-Tischplatte      Sitz und R\u00fcckenlehne aus synthetischem Rattan        Ma\u00dfe : 168x87x75 cm und 45x58x85cm","og_url":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/","og_site_name":"Kerama","article_publisher":"https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard%c3%adn-106209328312568\/","article_modified_time":"2025-01-15T10:24:03+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/","url":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/","name":"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168x87 - Ceramik &amp; Modena - Kerama","isPartOf":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/#primaryimage"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/#primaryimage"},"thumbnailUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","datePublished":"2024-04-02T14:10:16+00:00","dateModified":"2025-01-15T10:24:03+00:00","breadcrumb":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/#primaryimage","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/set-essgarten-6-sitzer-tisch-keramik-senf-168x87-ceramik-modena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keramamueblesdejardin.com\/de\/"},{"@type":"ListItem","position":2,"name":"Laden","item":"https:\/\/keramamueblesdejardin.com\/de\/laden\/"},{"@type":"ListItem","position":3,"name":"Speises\u00e4le im Freien","item":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/"},{"@type":"ListItem","position":4,"name":"Gartentisch- und Stuhlgarnitur","item":"https:\/\/keramamueblesdejardin.com\/de\/speisesale-im-freien\/gartentisch-und-stuhlgarnitur\/"},{"@type":"ListItem","position":5,"name":"Garten-Esszimmergarnitur 6-Sitzer-Keramik-Senftisch 168&#215;87 &#8211; Ceramik &amp; Modena"}]},{"@type":"WebSite","@id":"https:\/\/keramamueblesdejardin.com\/de\/#website","url":"https:\/\/keramamueblesdejardin.com\/de\/","name":"Kerama","description":"muebles de jard\u00edn","publisher":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keramamueblesdejardin.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/keramamueblesdejardin.com\/de\/#organization","name":"kerama","url":"https:\/\/keramamueblesdejardin.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/keramamueblesdejardin.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","contentUrl":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2020\/12\/k.-scaled.jpg","width":2560,"height":551,"caption":"kerama"},"image":{"@id":"https:\/\/keramamueblesdejardin.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kerama-Muebles-de-Jard\u00edn-106209328312568\/"]}]}},"df_price":1679,"df_sale_price":1679,"df_regular_price":1997,"df_image_link":"https:\/\/keramamueblesdejardin.com\/wp-content\/uploads\/2024\/04\/168-6-modena-mostaza-300x300.jpg","custom_tabs":[{"title":"MESSUNG","id":"messung","content":"<div class=\"list\">\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">H\u00f6he: <\/strong>Tisch 75cm \/ Stuhl 85cm<\/div>\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">Breite: <\/strong>Tisch 168cm \/ Stuhl 45cm<\/div>\n<div class=\"list\" style=\"color: #282828;\"><strong style=\"font-weight: bold;\">Unten: <\/strong>Tisch 87cm \/ Stuhl 58cm<\/div>\n<\/div>"},{"title":"AUSPACKEN UND MONTIEREN","id":"auspacken-und-montieren","content":"<div class=\"list\"><strong style=\"font-weight: bold; color: #282828;\">Empfehlungen zum<\/strong> Auspacken: <span style=\"color: #282828;\"> Verwenden Sie beim Auspacken der M\u00f6bel keine scharfen Utensilien, da dies zu Besch\u00e4digungen f\u00fchren kann<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Montage erforderlich (ja\/nein):<\/strong><span style=\"color: #282828;\"> Ja<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Schwierigkeitsgrad der Montage:<\/strong><span style=\"color: #282828;\"> Niedrig<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Montagezeit:<\/strong><span style=\"color: #282828;\"> 40 Minuten<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Empfohlene Personen f\u00fcr die Montage:<\/strong><span style=\"color: #282828;\"> 2<\/span><br style=\"color: #282828;\"><strong style=\"font-weight: bold; color: #282828;\">Montagevorschl\u00e4ge:<\/strong><span style=\"color: #282828;\">  Bereiten Sie einen sauberen und trockenen Montagebereich vor und stellen Sie sicher, dass keines der im Handbuch angegebenen Teile fehlt. Wir empfehlen das Tragen von Montagehandschuhen. Verwenden Sie nur die mitgelieferten Teile und Hardware.<\/span><\/div>"},{"title":"WARTUNG UND GARANTIEN","id":"wartung-und-garantien","content":"<strong>Allgemeine Empfehlungen:<\/strong>\n\u2022 Pannen oder Sch\u00e4den, die verursacht werden durch:\n\u2022 Zuf\u00e4llige Ursachen wie St\u00fcrze, Schl\u00e4ge, Versch\u00fctten von Fl\u00fcssigkeiten, Einschleppen von Fremdk\u00f6rpern sowie andere h\u00f6here Gewalt.\n\u2022 Fahrl\u00e4ssiger, unsachgem\u00e4\u00dfer oder nicht h\u00e4uslicher Gebrauch.\n\u2022 Besch\u00e4digung, Korrosion und\/oder Oxidation beschleunigt durch widrige Umweltbedingungen\n\u2022 Flecken und Verf\u00e4rbungen durch Nichtbeachtung unserer Reinigungsanweisungen\n\u2022 Sch\u00e4den, die w\u00e4hrend der Montage und Handhabung auftreten, ohne die angegebenen Montageanweisungen befolgt zu haben.\n<strong>Gebrauchs- und Wartungshinweise:<\/strong>\n\u2022 Reinigen Sie mit Hilfe eines Tuchs vorsichtig oder verwenden Sie eine neutrale Fl\u00fcssigseife und sp\u00fclen Sie sie mit viel Wasser ab.\n\u2022 Entfernen Sie Staub regelm\u00e4\u00dfig mit Hilfe eines weichen Tuchs und klarem Wasser.\n\u2022 Verwenden Sie zum Reinigen keine Reinigungsmittel oder Scheuermittel.\n\u2022 Behandlung mit Lein\u00f6l: Vor dem Auftragen einer Schicht Lein\u00f6l auf das Produkt in seinem nat\u00fcrlichen Zustand ist es ratsam, es 2 bis 3 Wochen im Freien stehen zu lassen, um ein homogenes Aussehen zu erhalten und es zu bel\u00fcften. Mit einer B\u00fcrste mit klarem Wasser reinigen und trocknen lassen. Sobald es gut getrocknet ist, sollte es mit einem Schleifpapier mit einer Grammatur zwischen 120 und 150 sorgf\u00e4ltig und ohne Anziehen geschliffen werden, wobei so weit wie m\u00f6glich der Richtung der Adern gefolgt werden sollte. Diese Operation wird niemals in den fr\u00fchen Morgenstunden durchgef\u00fchrt.\nUm die Farbe zu erhalten, ist es ratsam, den Vorgang ein- bis zweimal im Jahr zu wiederholen.\nWenn die M\u00f6bel bereits mit Lein\u00f6l bestrichen wurden, ist es ratsam, sie alle drei Jahre zu schleifen, damit die aufeinanderfolgenden \u00d6lschichten das Schwitzen des Holzes nicht verhindern.\nJahre <strong>Garantie: 3 Jahre<\/strong>\n<strong>Hergestellt nach Norm:<\/strong> 581-1.581-2.581-3\n<strong>FSC-Zertifizierung (ja\/nein):<\/strong> Ja"}],"_links":{"self":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product\/154412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/comments?post=154412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/media\/148528"}],"wp:attachment":[{"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/media?parent=154412"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_brand?post=154412"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_cat?post=154412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keramamueblesdejardin.com\/de\/wp-json\/wp\/v2\/product_tag?post=154412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}